{"id":6042,"date":"2018-05-10T13:10:42","date_gmt":"2018-05-10T17:10:42","guid":{"rendered":"https:\/\/www.jobillico.com\/blog\/?p=6042"},"modified":"2019-11-26T15:19:10","modified_gmt":"2019-11-26T20:19:10","slug":"google-job","status":"publish","type":"post","link":"https:\/\/www.jobillico.com\/blog\/google-job\/","title":{"rendered":"Comment publier une offre d\u2019emploi sur Google"},"content":{"rendered":"<p>Depuis avril 2018, tous les chercheurs d\u2019emploi au Canada peuvent d\u00e9sormais consulter les offres d\u2019emploi qui r\u00e9pondent \u00e0 des recherches comme \u00ab\u2009emplois pr\u00e8s de chez moi\u2009\u00bb, \u00ab\u2009emploi enseignant Montr\u00e9al\u2009\u00bb ou \u00ab\u2009emplois Jobillico Qu\u00e9bec\u2009\u00bb dans l\u2019outil de recherche d\u2019emplois de Google, maintenant disponible partout au pays.<\/p>\n<p>Comment de petites entreprises peuvent-elles profiter de cette nouvelle visibilit\u00e9 et voir leurs offres d\u2019emploi au sommet des r\u00e9sultats de recherche?<\/p>\n<p>D\u00e9couvrez tout ce qu\u2019il faut savoir pour publier une offre d\u2019emploi sur Google for Jobs et r\u00e9ussir \u00e0 rendre vos offres attrayantes pour les chercheurs d\u2019emploi.<\/p>\n<h2>C\u2019est quoi, le nouvel outil de recherche d\u2019emplois de Google?<\/h2>\n<p>Ce nouvel outil agit comme un agr\u00e9gateur. Il r\u00e9pertorie les offres d\u2019emploi affich\u00e9es sur une multitude de sites d\u2019emploi et les rend ensuite visibles directement sur la page de son moteur de recherche. Ainsi, pour le chercheur d\u2019emploi, un poste peut sembler \u00eatre affich\u00e9 directement sur l\u2019outil de Google.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-6081\" src=\"\/blog\/wp-content\/uploads\/2018\/05\/3-meilleurs-resultats-recherche-demploi-sur-google.jpg\" alt=\"3 meilleurs resultats recherche d'emploi sur google\" width=\"80%\" height=\"auto\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/3-meilleurs-resultats-recherche-demploi-sur-google.jpg 670w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/3-meilleurs-resultats-recherche-demploi-sur-google-300x333.jpg 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/3-meilleurs-resultats-recherche-demploi-sur-google-120x133.jpg 120w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/p>\n<p><!--\n\n\n<h3>Voici comment faire une recherche d\u2019emploi sur Google<\/h3>\n\n\nRechercher les meilleures offres d\u2019emploi sur Google\n\nPr\u00e9sentation des 3 offres les plus pertinentes\u00a0:\n\nVoici l\u2019aper\u00e7u d\u2019une offre (Exemple de notre client <a href=\"\/voir-entreprise\/rbc-uiymvf\">RBC<\/a> se retrouvant sur Google)\u00a0:\n\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6082 test\" src=\"\/blog\/wp-content\/uploads\/2018\/05\/detail-dune-offre-demploi-sur-google.jpg\" alt=\"detail d'une offre d'emploi sur google\" width=\"764\" height=\"781\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/detail-dune-offre-demploi-sur-google.jpg 764w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/detail-dune-offre-demploi-sur-google-300x307.jpg 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/detail-dune-offre-demploi-sur-google-700x716.jpg 700w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/detail-dune-offre-demploi-sur-google-120x123.jpg 120w\" sizes=\"auto, (max-width: 764px) 100vw, 764px\" \/>\n\nFiltrer les emplois\n\nLes chercheurs d\u2019emploi ont la possibilit\u00e9 de filtrer leurs r\u00e9sultats de recherche par cat\u00e9gorie d\u2019emploi, par titre, par localisation, par date d\u2019affichage, par statut d\u2019emploi (temps plein, temps partiel, stage), par industrie ou m\u00eame par employeur pr\u00e9f\u00e9r\u00e9.\n\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6083\" src=\"\/blog\/wp-content\/uploads\/2018\/05\/filtres-recherche-emploi-google.jpg\" alt=\"filtres recherche emploi google - journalier quebec\" width=\"1476\" height=\"569\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/filtres-recherche-emploi-google.jpg 1476w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/filtres-recherche-emploi-google-300x116.jpg 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/filtres-recherche-emploi-google-768x296.jpg 768w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/filtres-recherche-emploi-google-700x270.jpg 700w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/filtres-recherche-emploi-google-120x46.jpg 120w\" sizes=\"auto, (max-width: 1476px) 100vw, 1476px\" \/>\n\nSauvegarder et partager les offres d\u2019emploi\n\nIl est \u00e9galement possible de sauvegarder des offres ou de les partager.\n\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6084\" src=\"\/blog\/wp-content\/uploads\/2018\/05\/enregistrer-un-emploi-sur-google-canada.jpg\" alt=\"enregistrer un emploi sur google canada\" width=\"1577\" height=\"711\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/enregistrer-un-emploi-sur-google-canada.jpg 1577w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/enregistrer-un-emploi-sur-google-canada-300x135.jpg 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/enregistrer-un-emploi-sur-google-canada-768x346.jpg 768w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/enregistrer-un-emploi-sur-google-canada-700x316.jpg 700w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/enregistrer-un-emploi-sur-google-canada-1536x693.jpg 1536w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/enregistrer-un-emploi-sur-google-canada-120x54.jpg 120w\" sizes=\"auto, (max-width: 1577px) 100vw, 1577px\" \/>\n\n\u00c9l\u00e9ments distinctifs qui se retrouvent sur les offres affich\u00e9es dans Google\n\nSalaire moyen\n\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6047\" src=\"\/blog\/wp-content\/uploads\/2018\/05\/typical-pay-feature-in-google-for-jobs.jpg\" alt=\"typical pay feature in google for jobs\" width=\"1000\" height=\"231\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/typical-pay-feature-in-google-for-jobs.jpg 1000w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/typical-pay-feature-in-google-for-jobs-300x69.jpg 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/typical-pay-feature-in-google-for-jobs-768x177.jpg 768w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/typical-pay-feature-in-google-for-jobs-700x162.jpg 700w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/typical-pay-feature-in-google-for-jobs-120x28.jpg 120w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\n\nComparaison de salaires\n\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6090\" src=\"\/blog\/wp-content\/uploads\/2018\/05\/comparaison-salaire-recherche-emploi-google.jpg\" alt=\"comparaison-salaire-recherche-emploi-google\" width=\"998\" height=\"231\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/comparaison-salaire-recherche-emploi-google.jpg 998w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/comparaison-salaire-recherche-emploi-google-300x69.jpg 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/comparaison-salaire-recherche-emploi-google-768x178.jpg 768w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/comparaison-salaire-recherche-emploi-google-700x162.jpg 700w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/comparaison-salaire-recherche-emploi-google-120x28.jpg 120w\" sizes=\"auto, (max-width: 998px) 100vw, 998px\" \/>\n\u00c9valuation des employeurs\n\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6088\" src=\"\/blog\/wp-content\/uploads\/2018\/05\/evaluations-d-entreprises-emplois-google.jpg\" alt=\"evaluations-d-entreprises-emplois-google\" width=\"998\" height=\"208\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/evaluations-d-entreprises-emplois-google.jpg 998w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/evaluations-d-entreprises-emplois-google-300x63.jpg 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/evaluations-d-entreprises-emplois-google-768x160.jpg 768w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/evaluations-d-entreprises-emplois-google-700x146.jpg 700w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/evaluations-d-entreprises-emplois-google-120x25.jpg 120w\" sizes=\"auto, (max-width: 998px) 100vw, 998px\" \/>\n\nCarte\n\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6089\" src=\"\/blog\/wp-content\/uploads\/2018\/05\/jobillico-quebec-map-sur-google-jobs.jpg\" alt=\"jobillico quebec map sur google jobs\" width=\"991\" height=\"372\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/jobillico-quebec-map-sur-google-jobs.jpg 991w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/jobillico-quebec-map-sur-google-jobs-300x113.jpg 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/jobillico-quebec-map-sur-google-jobs-768x288.jpg 768w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/jobillico-quebec-map-sur-google-jobs-700x263.jpg 700w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/jobillico-quebec-map-sur-google-jobs-120x45.jpg 120w\" sizes=\"auto, (max-width: 991px) 100vw, 991px\" \/>--><\/p>\n<h2>Comment publier une offre d\u2019emploi dans le moteur de recherche de Google?<\/h2>\n<p>Google n\u2019est pas une plateforme sur laquelle vous pouvez tout simplement d\u00e9poser votre offre pour la voir se retrouver sur son site. En tant qu\u2019agr\u00e9gateur, le moteur de recherche proc\u00e8de plut\u00f4t en allant chercher les offres qui se retrouvent sur diff\u00e9rents sites, comme celui de Jobillico.<\/p>\n<p>Si vous souhaitez que vos offres soient visibles sur Google, vous devez lui faire comprendre o\u00f9 elles se retrouvent. Il y a deux fa\u00e7ons d\u2019y arriver.<\/p>\n<h3>#1 \u2013 Structurer vos offres pour qu\u2019elles soient d\u00e9tect\u00e9es par Google.<\/h3>\n<ol>\n<li>Faites en sorte que vos offres puissent \u00eatre trouv\u00e9es facilement sur le web (elles ne doivent pas \u00eatre prot\u00e9g\u00e9es par un fichier robots.txt ou par un META tag robot).<\/li>\n<li>Ajoutez des <a href=\"https:\/\/developers.google.com\/search\/docs\/data-types\/job-posting#definitions\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">donn\u00e9es structur\u00e9es<\/a> \u00e0 vos offres d\u2019emploi.<\/li>\n<li>Informez Google de tout changement dans vos offres d\u2019emploi avec le <a href=\"https:\/\/developers.google.com\/search\/docs\/data-types\/job-posting#sitemap-guidelines\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">sitemaps<\/a> de Google, souvent mis \u00e0 jour.<\/li>\n<\/ol>\n<p>Dans le <a href=\"https:\/\/developers.google.com\/search\/docs\/data-types\/job-posting\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">guide officiel de Google<\/a>, vous trouverez comment ajouter les balises n\u00e9cessaires sur votre site pour rendre possible la publication de vos offres dans le moteur de recherche de Google.<\/p>\n<h3>#2 \u2013 Publier vos offres \u00e0 partir d\u2019un site partenaire de Google, comme celui de Jobillico.<\/h3>\n<p>Les offres d\u2019emploi publi\u00e9es sur le site de Jobillico sont automatiquement programm\u00e9es pour qu\u2019elles soient d\u00e9tect\u00e9es par l\u2019outil de recherche de Google et ensuite visibles sur son moteur de recherche.<\/p>\n<p><a class=\"c-single-button\" href=\"\/fr\/joindre-reseau\">D\u00e9couvrez comment publier vos offres chez Jobillico!<\/a><\/p>\n<h2>Comment classer mon offre au sommet des r\u00e9sultats de recherche dans Google?<\/h2>\n<h3>#1 &#8211; R\u00e9digez une offre d\u2019emploi attrayante.<\/h3>\n<p>Personne ne peut vraiment savoir quel est l\u2019algorithme de Google. Mais, ce que l\u2019on sait, c\u2019est qu\u2019une offre d\u2019emploi attrayante obtient beaucoup plus de r\u00e9sultats. C\u2019est pourquoi Jobillico vous a rassembl\u00e9 diff\u00e9rentes notions importantes pour <a href=\"\/ecrire-une-offre-demploi\/?lang=fr\">bien r\u00e9diger une offre d\u2019emploi pour le web<\/a> et augmenter vos chances de les voir figurer au sommet des r\u00e9sultats de recherche sur Google.<\/p>\n<h3>#2 &#8211; Assurez-vous d\u2019inscrire des informations qui sauront convaincre les chercheurs d\u2019emploi.<\/h3>\n<p>Une offre qui manque d\u2019information semble tout simplement vide.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6092\" src=\"\/blog\/wp-content\/uploads\/2018\/05\/publier-offre-emploi-avec-description-sur-google.jpg\" alt=\"publier-offre-emploi-avec-description-sur-google\" width=\"998\" height=\"502\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/publier-offre-emploi-avec-description-sur-google.jpg 998w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/publier-offre-emploi-avec-description-sur-google-300x151.jpg 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/publier-offre-emploi-avec-description-sur-google-768x386.jpg 768w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/publier-offre-emploi-avec-description-sur-google-700x352.jpg 700w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/publier-offre-emploi-avec-description-sur-google-120x60.jpg 120w\" sizes=\"auto, (max-width: 998px) 100vw, 998px\" \/><\/p>\n<h3>#3 \u2013 Prenez soin de bien structurer les informations et de les rendre dans un format lisible.<\/h3>\n<p>Si la description de votre offre ressemble \u00e0 ceci, le taux de lecture chutera drastiquement.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6093\" src=\"\/blog\/wp-content\/uploads\/2018\/05\/structurer-offre-emploi-sur-google-avant-de-publier.jpg\" alt=\"structurer-offre-emploi-sur-google-avant-de-publier\" width=\"1017\" height=\"666\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/structurer-offre-emploi-sur-google-avant-de-publier.jpg 1017w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/structurer-offre-emploi-sur-google-avant-de-publier-300x196.jpg 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/structurer-offre-emploi-sur-google-avant-de-publier-768x503.jpg 768w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/structurer-offre-emploi-sur-google-avant-de-publier-700x458.jpg 700w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/structurer-offre-emploi-sur-google-avant-de-publier-120x79.jpg 120w\" sizes=\"auto, (max-width: 1017px) 100vw, 1017px\" \/><\/p>\n<p>Pensez \u00e0 ajouter du code HTML dans le champ description pour un meilleur affichage. (Testez votre offre d&#8217;emploi dans l&rsquo;<a href=\"https:\/\/search.google.com\/structured-data\/testing-tool\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">outil de test des donn\u00e9es structur\u00e9es<\/a>)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6094\" src=\"\/blog\/wp-content\/uploads\/2018\/05\/comment-ajouter-html-offre-emploi-publiee-sur-google-jobillico.jpg\" alt=\"comment-ajouter-html-offre-emploi-publiee-sur-google-jobillico\" width=\"895\" height=\"332\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/comment-ajouter-html-offre-emploi-publiee-sur-google-jobillico.jpg 895w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/comment-ajouter-html-offre-emploi-publiee-sur-google-jobillico-300x111.jpg 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/comment-ajouter-html-offre-emploi-publiee-sur-google-jobillico-768x285.jpg 768w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/comment-ajouter-html-offre-emploi-publiee-sur-google-jobillico-700x260.jpg 700w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2018\/05\/comment-ajouter-html-offre-emploi-publiee-sur-google-jobillico-120x45.jpg 120w\" sizes=\"auto, (max-width: 895px) 100vw, 895px\" \/><\/p>\n<h3>#4 \u2013 Publiez plusieurs offres.<\/h3>\n<p>Les compagnies qui publient plusieurs offres diff\u00e9rentes \u00e0 partir d\u2019une m\u00eame plateforme voient souvent leur nombre de CV re\u00e7us grimper.<\/p>\n<h2>Comment mesurer le trafic sur vos offres r\u00e9pertori\u00e9es sur Google?<\/h2>\n<p>Dans la <a href=\"https:\/\/www.google.com\/webmasters\/tools\/home?hl=fr&amp;pli=1\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Search Console<\/a> de Google, il est possible d\u2019observer le nombre de clics et d\u2019impressions, le taux de clics et la position de vos offres dans les listes de r\u00e9sultats de recherche. De plus, comme Google associe automatiquement un lien UTM \u00e0 l\u2019adresse URL de votre offre, vous pouvez suivre vos offres et leur port\u00e9e sur Google Analytics.<\/p>\n<h2>\u00c0 faire et \u00e0 ne pas faire quand on veut retrouver nos offres sur Google<\/h2>\n<p><strong>\u00c0 faire&nbsp;: <\/strong><\/p>\n<p>Publier une offre d\u2019emploi pour un poste disponible au sein de votre entreprise et sur laquelle un chercheur d\u2019emploi peut postuler. Ne laissez pas d\u2019offres expir\u00e9es sur le web.<\/p>\n<p><strong>\u00c0 faire&nbsp;: <\/strong><\/p>\n<p>Ajouter des balises dans le texte de l\u2019offre d\u2019emploi pour structurer l\u2019information pr\u00e9sent\u00e9e.<\/p>\n<p><strong>\u00c0 faire&nbsp;: <\/strong><\/p>\n<p>Mettre votre sitemap \u00e0 jour au moins quotidiennement.<\/p>\n<p><strong>\u00c0 ne pas faire&nbsp;: <\/strong><\/p>\n<p>Ajouter des donn\u00e9es structur\u00e9es \u00e0 l\u2019URL de l\u2019offre ou \u00e0 une page qui ne fait que pr\u00e9senter une liste d\u2019offres d\u2019emploi.<\/p>\n<p><strong>\u00c0 ne pas faire&nbsp;: <\/strong><\/p>\n<p>Ajouter une balise \u00ab\u2009offre d\u2019emploi\u2009\u00bb \u00e0 une page qui ne pr\u00e9sente pas d\u2019offres d\u2019emploi, publier une offre sans moyen de postulation, publier une offre pour laquelle il faut payer pour postuler, et plus encore. Pour lire une liste compl\u00e8te, <a href=\"https:\/\/developers.google.com\/search\/docs\/data-types\/job-posting#policies\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">cliquez ici<\/a>.<\/p>\n<p><strong>\u00c0 ne pas faire&nbsp;: <\/strong><\/p>\n<p>Laisser sur le web des offres d\u2019emploi expir\u00e9es ou des liens URL supprim\u00e9s.<\/p>\n<h2>Questions\/R\u00e9ponses en rafale<\/h2>\n<h3>Quels outils utiliser pour voir mes offres d\u2019emploi apparaitre dans Google?<\/h3>\n<p>Google offre plusieurs outils pour vous aider \u00e0 int\u00e9grer vos offres sur son site de recherche d\u2019offres d\u2019emploi. Vous pouvez entre autres valider vos offres avec l\u2019<a href=\"https:\/\/search.google.com\/structured-data\/testing-tool\/u\/0\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Outil de test des donn\u00e9es structur\u00e9es<\/a>, v\u00e9rifier la compatibilit\u00e9 avec Google gr\u00e2ce au <a href=\"https:\/\/search.google.com\/test\/rich-results\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Test des r\u00e9sultats enrichis<\/a> et suivre l\u2019activit\u00e9 sur votre offre avec <a href=\"https:\/\/www.google.com\/webmasters\/tools\/home?hl=fr&amp;pli=1\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Google Search Console<\/a>.<\/p>\n<h3>Quel est l\u2019aspect le plus important \u00e0 consid\u00e9rer si je souhaite retrouver mon offre d\u2019emploi sur Google?<\/h3>\n<p>Suivez la documentation de <a href=\"https:\/\/developers.google.com\/search\/docs\/data-types\/job-posting#JobPosting-definition rel=\">Google<\/a> et de <a href=\"http:\/\/schema.org\/JobPosting\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Schema.org<\/a> lorsque vous cr\u00e9ez votre offre.<\/p>\n<h3>Comment ajouter des balises \u00e0 mon offre d\u2019emploi?<\/h3>\n<p>Pour indiquer \u00e0 Google o\u00f9 se trouve votre offre d\u2019emploi, vous devez y ajouter des microdatas ou des donn\u00e9es structur\u00e9es de type JSON. Pour ce faire, vous pouvez tout simplement faire appel \u00e0 votre webmestre ou bien contacter Jobillico. Puisque Jobillico est partenaire avec Google, la structure de son site vous permet automatiquement de rendre vos offres visibles pour Google.<\/p>\n<h3>Comment savoir combien de mes offres d\u2019emploi se retrouvent dans Google?<\/h3>\n<p>Faites une recherche et consultez le <a href=\"https:\/\/support.google.com\/webmasters\/answer\/6381755?vid=0-1039621575546-1524249657007\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Rich Cards Reports<\/a>.<\/p>\n<h3>Quoi faire lorsqu\u2019une offre ne s\u2019affiche pas ou qu\u2019elle ne s\u2019affiche pas correctement sur Google?<\/h3>\n<p>Voici les probl\u00e8mes les plus communs&nbsp;:<\/p>\n<h4>Une offre d\u2019emploi n\u2019apparait pas.<\/h4>\n<p>Plusieurs facteurs peuvent expliquer le fait que votre offre d\u2019emploi n\u2019apparait pas sur Google.<\/p>\n<p>Voici ce que vous pouvez faire&nbsp;:<\/p>\n<ul>\n<li>V\u00e9rifiez si votre page est index\u00e9e sur Google en faisant une simple recherche. Par exemple, vous pouvez inscrire dans le moteur de recherche Google la page que vous souhaitez trouver, du genre votresite.com\/votreoffredemploi. Si la page n\u2019apparait pas dans les r\u00e9sultats de recherche, cela signifie que votre page n\u2019est pas index\u00e9e. Dans ce cas, Google ne sera pas en mesure de r\u00e9pertorier votre offre dans son moteur de recherche. Pour r\u00e9soudre la situation, vous devez v\u00e9rifier si votre page est bloqu\u00e9e par un robots.txt ou par des META tags.<\/li>\n<li>V\u00e9rifiez la validit\u00e9 de vos balises avec l\u2019<a href=\"https:\/\/search.google.com\/structured-data\/testing-tool\/u\/0\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Outil de test des donn\u00e9es structur\u00e9es<\/a>.<\/li>\n<li><a href=\"https:\/\/support.google.com\/webmasters\/answer\/183669\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">G\u00e9rez votre sitemap<\/a> dans Search Console.<\/li>\n<li><a href=\"https:\/\/support.google.com\/webmasters\/answer\/6381755?vid=0-1039621575546-1524249657007\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Renseignez-vous sur les diff\u00e9rentes erreurs reli\u00e9es aux balises d\u2019un site<\/a> et analysez la possibilit\u00e9 d\u2019apporter des am\u00e9liorations au v\u00f4tre.<\/li>\n<\/ul>\n<h4>Votre logo n\u2019apparait pas.<\/h4>\n<p>Pour vous assurer que votre logo d\u2019entreprise s\u2019affiche dans vos offres qui se retrouvent sur Google, ajoutez-le \u00e0 vos comptes Google My Business et YouTube.<\/p>\n<p>Si l\u2019affichage de vos offres sur Google \u00e0 partir du site web de votre entreprise vous semble une t\u00e2che trop complexe, n\u2019h\u00e9sitez pas \u00e0 nous contacter. Comme Jobillico est partenaire avec Google, toutes les offres d\u2019emploi publi\u00e9es sur notre site sont format\u00e9es pour \u00eatre visibles par le g\u00e9ant mondial de la recherche sur le web.<\/p>\n","protected":false},"excerpt":{"rendered":"Depuis avril 2018, tous les chercheurs d\u2019emploi au Canada peuvent d\u00e9sormais consulter les offres d\u2019emploi qui r\u00e9pondent \u00e0 des recherches comme \u00ab\u2009emplois pr\u00e8s de chez moi\u2009\u00bb, \u00ab\u2009emploi enseignant Montr\u00e9al\u2009\u00bb ou \u00ab\u2009emplois Jobillico Qu\u00e9bec\u2009\u00bb dans l\u2019outil de recherche d\u2019emplois de Google, maintenant disponible partout au pays","protected":false},"author":19,"featured_media":8637,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[484],"tags":[],"class_list":["post-6042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rh"],"_links":{"self":[{"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/posts\/6042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/comments?post=6042"}],"version-history":[{"count":30,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/posts\/6042\/revisions"}],"predecessor-version":[{"id":11462,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/posts\/6042\/revisions\/11462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/media\/8637"}],"wp:attachment":[{"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/media?parent=6042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/categories?post=6042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/tags?post=6042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}