{"id":4543,"date":"2016-11-22T07:55:22","date_gmt":"2016-11-22T12:55:22","guid":{"rendered":"https:\/\/www.jobillico.com\/blog\/?p=4543"},"modified":"2018-12-20T13:52:26","modified_gmt":"2018-12-20T18:52:26","slug":"4-looks-inspiration-pinterest-travail","status":"publish","type":"post","link":"https:\/\/www.jobillico.com\/blog\/4-looks-inspiration-pinterest-travail\/","title":{"rendered":"4 looks d\u2019inspiration Pinterest pour le travail"},"content":{"rendered":"<p>D\u2019abord, la veille (le dimanche par exemple) je planifie mes <em>kits<\/em> pour la semaine. Comme \u00e7a, quand je me l\u00e8ve, tout est pr\u00eat, j\u2019ai fait ma r\u00e9flexion la veille. Si j\u2019ai une r\u00e9union ou une activit\u00e9 du club social, tout est planifi\u00e9!<\/p>\n<p>Apr\u00e8s \u00e7a, j\u2019accompagne mes tenues de ces morceaux classiques inspir\u00e9s de Pinterest et d\u2019Audrey Hepburn.<\/p>\n<h2 class=\"soustitre\"><b>Le fameux ensemble veston-jeans<\/b><\/h2>\n<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 45%;\"><a href=\"\/blog\/wp-content\/uploads\/2016\/10\/veston-jeans-travail.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-4547\" src=\"\/blog\/wp-content\/uploads\/2016\/10\/veston-jeans-travail.png\" alt=\"veston-jeans-travail\" width=\"75%\" height=\"75%\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2016\/10\/veston-jeans-travail.png 532w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2016\/10\/veston-jeans-travail-300x419.png 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2016\/10\/veston-jeans-travail-120x168.png 120w\" sizes=\"(max-width: 532px) 100vw, 532px\" \/><\/a><\/td>\n<td style=\"width: 10%;\"><\/td>\n<td style=\"width: 45%;\">Je sais, certains environnements de travail obligent le port du pantalon noir (avec quelques <i>casual fridays<\/i>), mais pour celles qui peuvent se le permettre, je trouve cet ensemble merveilleux. C\u2019est un excellent compromis entre la femme professionnelle et la fille d\u00e9contract\u00e9e. C\u2019est urbain et propre en m\u00eame temps. De plus en plus d\u2019entreprises permettent ce code vestimentaire.<\/p>\n<p>Photo:&nbsp;All Women\u2019s Talk<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 class=\"soustitre\"><b>L\u2019ensemble noir chic et d\u00e9contract\u00e9<\/b><\/h2>\n<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 45%;\"><a href=\"\/blog\/wp-content\/uploads\/2016\/10\/chandail-noir-travail.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-4552\" src=\"\/blog\/wp-content\/uploads\/2016\/10\/chandail-noir-travail.png\" alt=\"chandail-noir-travail\" width=\"75%\" height=\"75%\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2016\/10\/chandail-noir-travail.png 525w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2016\/10\/chandail-noir-travail-300x447.png 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2016\/10\/chandail-noir-travail-120x179.png 120w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/a><\/td>\n<td style=\"width: 10%;\"><\/td>\n<td style=\"width: 45%;\">\u00c0 force de ne pas savoir quoi porter, je me suis mise \u00e0 m\u2019habiller souvent en noir. Non pas que j\u2019aime particuli\u00e8rement le noir, mais c\u2019est ce qui est le plus passe-partout. Tu peux avoir un chandail qui ne fait pas si \u00ab&nbsp;travail de bureau&nbsp;\u00bb, mais qui passe le test parce qu\u2019il est noir. Surtout si tu mets un collier ou un cardigan pour agr\u00e9menter ta tenue. C\u2019est pour \u00e7a que j\u2019ai eu un coup de c\u0153ur pour ce look&nbsp;: c\u2019est \u00e9l\u00e9gant, mais pas trop corpo.<\/p>\n<p>Photo:http:\/\/www.careergirldaily.com\/<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 class=\"soustitre\"><b>La petite blouse fluide en V qu\u2019on voit partout<\/b><\/h2>\n<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 45%;\"><a href=\"\/blog\/wp-content\/uploads\/2016\/10\/blouse-noire.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-4554\" src=\"\/blog\/wp-content\/uploads\/2016\/10\/blouse-noire.png\" alt=\"blouse-noire\" width=\"80%\" height=\"80%\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2016\/10\/blouse-noire.png 416w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2016\/10\/blouse-noire-300x332.png 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2016\/10\/blouse-noire-120x133.png 120w\" sizes=\"(max-width: 416px) 100vw, 416px\" \/><\/a><\/td>\n<td style=\"width: 10%;\"><\/td>\n<td style=\"width: 45%;\">Ce type de blouse, on le voit partout. Je crois qu\u2019il n\u2019y a pas une boutique de v\u00eatements o\u00f9 je ne l\u2019ai pas vu. Je sais, ce n\u2019est pas ce qu\u2019il y a de plus original, mais disons que c\u2019est la blouse qui d\u00e9panne. C\u2019est simple, propre et \u00e7a nous donne habituellement une belle coupe. \u00c7a se met facilement en dessous d\u2019un veston ou d\u2019un cardigan. Personne ne peut dire que tu ne respectes pas le code vestimentaire.<\/p>\n<p>Photo: Simons<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 class=\"soustitre\"><b>4. Le pantalon noir ample<\/b><\/h2>\n<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 45%;\"><a href=\"\/blog\/wp-content\/uploads\/2016\/10\/pantalon-noir-fluide-travail.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-4555\" src=\"\/blog\/wp-content\/uploads\/2016\/10\/pantalon-noir-fluide-travail.png\" alt=\"pantalon-noir-fluide-travail\" width=\"75%\" height=\"75%\" srcset=\"https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2016\/10\/pantalon-noir-fluide-travail.png 429w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2016\/10\/pantalon-noir-fluide-travail-300x442.png 300w, https:\/\/www.jobillico.com\/blog\/wp-content\/uploads\/2016\/10\/pantalon-noir-fluide-travail-120x177.png 120w\" sizes=\"(max-width: 429px) 100vw, 429px\" \/><\/a><\/td>\n<td style=\"width: 10%;\"><\/td>\n<td style=\"width: 45%;\">Un mot&nbsp;: CONFORT. J\u2019ai trouv\u00e9 deux paires de pantalons dans ce genre, et je les mets chaque semaine \u00e0 mon travail. C\u2019est non seulement propre quand on met un haut appropri\u00e9, mais c\u2019est tr\u00e8s confortable. Fini le pantalon noir \u00e0 tissu tr\u00e8s \u00e9pais classique. Je ne peux plus m\u2019en passer.<\/p>\n<p>Photo: Simons<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>J\u2019aurais encore pu parler du legging, des petites bottines noires ou de la jupe agenc\u00e9e avec une chemise, mais les mots me manquaient. Ce sont des petits looks de base tr\u00e8s pratiques pour aller travailler.<\/p>\n<p>Pour en voir davantage, tu peux \u00e9galement t\u2019inspirer de nos \u00e9pingles sur notre compte<a title=\"Pinterest\" href=\"https:\/\/www.pinterest.com\/jobillicoemploi\/mode-f%C3%A9minine-emploi\/\"> Pinterest<\/a>!<!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"J\u2019ai un travail de bureau avec un code vestimentaire particulier \u00e0 respecter. Je ne suis pas le genre fille qui se l\u00e8ve le matin et qui a envie de passer 3 heures devant mon garde-robe pour savoir quoi porter\u2026 mais j\u2019aime tout de m\u00eame \u00eatre \u00e0 la fois propre et d\u00e9contract\u00e9e. Alors, avec des morceaux bien de base,\u00a0 j\u2019ai arr\u00eat\u00e9 de me casser la t\u00eate pour choisir comment m\u2019habiller le matin!","protected":false},"author":2,"featured_media":4557,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[346],"tags":[],"class_list":["post-4543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carriere"],"_links":{"self":[{"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/posts\/4543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/comments?post=4543"}],"version-history":[{"count":5,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/posts\/4543\/revisions"}],"predecessor-version":[{"id":8038,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/posts\/4543\/revisions\/8038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/media\/4557"}],"wp:attachment":[{"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/media?parent=4543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/categories?post=4543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/tags?post=4543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}