{"id":13464,"date":"2020-12-03T09:45:00","date_gmt":"2020-12-03T14:45:00","guid":{"rendered":"https:\/\/www.jobillico.com\/blog\/?p=13464"},"modified":"2022-02-25T17:12:35","modified_gmt":"2022-02-25T22:12:35","slug":"comment-garder-vos-employes-pendant-la-pandemie","status":"publish","type":"post","link":"https:\/\/www.jobillico.com\/blog\/comment-garder-vos-employes-pendant-la-pandemie\/","title":{"rendered":"Comment garder vos employ\u00e9s pendant la pand\u00e9mie?"},"content":{"rendered":"\n<p>2020 a \u00e9t\u00e9 une ann\u00e9e pleine de d\u00e9fis personnels et professionnels pour tous. En plus de la pand\u00e9mie, nous avons \u00e9t\u00e9 oblig\u00e9s d\u2019adapter tous les aspects de nos vies. Le travail, la vie de famille, les vacances, le magasinage\u2026 Tout a chang\u00e9, ou presque.<\/p>\n\n\n\n<p>Pour le travail, \u00e7a a \u00e9t\u00e9 soit le t\u00e9l\u00e9travail, soit le travail au bureau avec respect strict des gestes barri\u00e8re et distanciation physique. Autant dire que ce n\u2019est pas toujours une partie de plaisir.<\/p>\n\n\n\n<p>Dans leurs courses \u00e0 l\u2019adaptation, de nombreux employeurs ont oubli\u00e9 des gestes qui retiennent la main-d&rsquo;\u0153uvre : renforcer la culture d\u2019entreprise, maintenir la coh\u00e9sion des \u00e9quipes et rassembler les employ\u00e9s autour d\u2019objectifs communs. Pour beaucoup, l\u2019adaptation a \u00e9t\u00e9 synonyme de fournir un ordinateur pour le t\u00e9l\u00e9travail ou de r\u00e9am\u00e9nager les espaces du bureau. N\u00e9cessaire, mais insuffisant, surtout apr\u00e8s des mois de pand\u00e9mie.<\/p>\n\n\n\n<p>Voici quelques attitudes et r\u00e9flexes \u00e0 adopter pour garder vos employ\u00e9s pendant et apr\u00e8s la pand\u00e9mie :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Renforcer la culture d\u2019entreprise<\/li><li>Se rapprocher de ses employ\u00e9s<\/li><li>Montrez-vous rassurant<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-renforcer-la-culture-d-entreprise\">Renforcer la culture d\u2019entreprise<\/h2>\n\n\n\n<p>Comme nous vous le disions en d\u00e9tail dans un article sur <a href=\"\/blog\/maintenir-culture-dentreprise-teletravail\/\" target=\"_blank\" rel=\"noreferrer noopener\">la culture d\u2019entreprise<\/a>, celle-ci ne se limite pas qu\u2019\u00e0 des \u00e9v\u00e9nements de style 5 \u00e0 7 ou sorties au restaurant. En bref, tout ce qu\u2019on ne peut pas faire actuellement \u00e0 cause de la pand\u00e9mie. Une culture d\u2019entreprise passe par une expertise en communication. Sinon, vos employ\u00e9s risquent de quitter le navire tr\u00e8s vite. D&rsquo;ailleurs, un sondage de la firme ADP, rapport\u00e9 par <a href=\"https:\/\/www.lesaffaires.com\/blogues\/olivier-schmouker\/41-des-quebecois-prets-a-changer-d-employeur-apres-la-pandemie\/618180\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Les Affaires<\/a>, rapporte que plus de 40% des Qu\u00e9b\u00e9cois sont pr\u00eats de changer d&#8217;employeur apr\u00e8s la pand\u00e9mie. <\/p>\n\n\n\n<p>En ces temps difficiles, il est important de faire ressortir vos valeurs et ce qui fait l\u2019ADN de votre entreprise. Le but est que vos employ\u00e9s se souviennent pourquoi ils travaillent avec vous et pas avec vos concurrents. Toutes sortes de r\u00e9compenses sont les bienvenues. La premi\u00e8re est la reconnaissance des efforts.<\/p>\n\n\n\n<p>Bien que vos employ\u00e9s soient pay\u00e9s, ils offrent une grande partie de leur temps pour agrandir votre entreprise. En ces temps difficiles, avoir de la reconnaissance et de l\u2019empathie est important. Votre \u00e9quipe a d\u00fb s&rsquo;adapter \u00e0 de nouveaux r\u00e9flexes et \u00e0 une forme d\u2019ins\u00e9curit\u00e9 permanente. Dites-vous qu\u2019ils m\u00e9ritent des am\u00e9nagements et des conditions de travail s\u00e9curitaires et confortables. Par la suite, assurez-vous de leur t\u00e9moigner votre gratitude.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-se-rapprocher-de-ses-employ-s\">Se rapprocher de ses employ\u00e9s<\/h2>\n\n\n\n<p>Soyez pr\u00e9sent de vos employ\u00e9s \u00e0 travers vos communications \u00e0 l\u2019interne ou \u00e0 l\u2019externe. Votre plus ancien employ\u00e9 f\u00eate ses 10 ans au sein de l\u2019entreprise? Prenez le temps de le mentionner \u00e0 l\u2019interne et sur vos r\u00e9seaux sociaux. Faites de m\u00eame pour une nouvelle recrue.<\/p>\n\n\n\n<p>Une entreprise qui met ses employ\u00e9s au c\u0153ur de sa croissance et de ses activit\u00e9s est une entreprise tr\u00e8s souvent prosp\u00e8re.<\/p>\n\n\n\n<p>Vous devez instaurer une proximit\u00e9 mesur\u00e9e avec vos employ\u00e9s afin qu\u2019ils montrent de la loyaut\u00e9 envers leur travail et envers votre entreprise.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-montrez-vous-rassurant\">Montrez-vous rassurant<\/h2>\n\n\n\n<p>Nous avons tous un besoin de sentiment de s\u00e9curit\u00e9, surtout en ces temps incertains. Comment l\u2019installer?<\/p>\n\n\n\n<p><br>Dans plusieurs secteurs, des emplois ont \u00e9t\u00e9 supprim\u00e9s, des travailleurs ont \u00e9t\u00e9 mis \u00e0 pied. Les plus chanceux peuvent ressentir un sentiment de stagnation et de routine harassante. C\u2019est le temps pour vous d\u2019\u00eatre rassurant.<\/p>\n\n\n\n<p>R\u00e9unissez vos employ\u00e9s et expliquez la situation de votre entreprise en toute transparence. Des emplois sont-ils en danger? Les affaires vont bien? Peu importe, vos collaborateurs doivent le savoir. C\u2019est toujours rassurant de travailler sans se dire que notre emploi peut dispara\u00eetre \u00e0 tout moment.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-promotion-l-interne-et-r-compenses\">Promotion \u00e0 l\u2019interne et r\u00e9compenses<\/h2>\n\n\n\n<p>Vous pouvez id\u00e9alement offrir la chance \u00e0 quelques-uns de vos employ\u00e9s de grandir au sein de votre entreprise. Si votre budget le permet, offrez des cadeaux, des augmentations de salaire \u00e0 des employ\u00e9s qui atteignent des r\u00e9sultats.<\/p>\n\n\n\n<p>Souvent, le recrutement peut co\u00fbter cher. Pourquoi ne pas investir dans votre propre main-d&rsquo;\u0153uvre?&nbsp; Votre charg\u00e9 de projets travaille avec vous depuis 3 ans? Il est efficace et travaille en \u00e9quipe? Pourquoi ne pas le nommer coordonnateur au lieu de le laisser partir chez votre concurrent? Ce genre de gestes peut vous sauver vos meilleurs joueurs, en plus de bonifier votre image d\u2019entreprise ax\u00e9e sur l\u2019\u00e9volution.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-pour-finir\">Pour finir\u2026<\/h2>\n\n\n\n<p>La pand\u00e9mie a chang\u00e9 bien des choses en mati\u00e8re de gestion des ressources humaines. D\u00e9sormais, vous devez faire un effort suppl\u00e9mentaire pour renforcer la synergie de vos \u00e9quipes. Reconnaissance, fid\u00e9lisation et entraide sont des actions \u00e0 prendre pour s\u2019adapter. Si vous n\u2019\u00eates pas \u00e0 l\u2019\u00e9coute des besoins de votre main-d&rsquo;\u0153uvre, vous risquez de la voir partir, au plus tard d\u00e8s le retour \u00e0 la normale.<\/p>\n","protected":false},"excerpt":{"rendered":"Comment garder ses employ\u00e9s pendant la pand\u00e9mie? Sachant que, nombreux sont ceux qui quitteront leur emploi apr\u00e8s la pand\u00e9mie.","protected":false},"author":26,"featured_media":13469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343,484],"tags":[4822],"class_list":["post-13464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestion-de-personnel","category-rh","tag-gestion-du-capital-humain"],"_links":{"self":[{"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/posts\/13464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/comments?post=13464"}],"version-history":[{"count":5,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/posts\/13464\/revisions"}],"predecessor-version":[{"id":15126,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/posts\/13464\/revisions\/15126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/media\/13469"}],"wp:attachment":[{"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/media?parent=13464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/categories?post=13464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jobillico.com\/blog\/wp-json\/wp\/v2\/tags?post=13464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}